{"id":6026,"date":"2025-10-31T10:50:58","date_gmt":"2025-10-31T03:50:58","guid":{"rendered":"https:\/\/bim-indonesia.id\/?page_id=6026"},"modified":"2025-10-31T10:51:07","modified_gmt":"2025-10-31T03:51:07","slug":"fan-fabrication-installation","status":"publish","type":"page","link":"https:\/\/bim-indonesia.id\/index.php\/fan-fabrication-installation\/","title":{"rendered":"Fan Fabrication &amp; Installation"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-6026","page","type-page","status-publish","hentry"],"yoast_head":"<title>Fan Fabrication &amp; Installation - BIM Indonesia<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fan Fabrication &amp; Installation - BIM Indonesia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bim-indonesia.id\/index.php\/fan-fabrication-installation\/\" \/>\n<meta property=\"og:site_name\" content=\"BIM Indonesia\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T03:51:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/index.php\\\/fan-fabrication-installation\\\/\",\"url\":\"https:\\\/\\\/bim-indonesia.id\\\/index.php\\\/fan-fabrication-installation\\\/\",\"name\":\"Fan Fabrication &amp; Installation - BIM Indonesia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/#website\"},\"datePublished\":\"2025-10-31T03:50:58+00:00\",\"dateModified\":\"2025-10-31T03:51:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/index.php\\\/fan-fabrication-installation\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bim-indonesia.id\\\/index.php\\\/fan-fabrication-installation\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/index.php\\\/fan-fabrication-installation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bim-indonesia.id\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fan Fabrication &amp; Installation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/#website\",\"url\":\"https:\\\/\\\/bim-indonesia.id\\\/\",\"name\":\"BIM Indonesia\",\"description\":\"Innovation  *  Quality  *  Service\",\"publisher\":{\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bim-indonesia.id\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/#organization\",\"name\":\"BIM Indonesia\",\"url\":\"https:\\\/\\\/bim-indonesia.id\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bim-indonesia.id\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-WhatsApp-Image-2024-05-16-at-20.37.34.jpeg\",\"contentUrl\":\"https:\\\/\\\/bim-indonesia.id\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-WhatsApp-Image-2024-05-16-at-20.37.34.jpeg\",\"width\":1075,\"height\":1076,\"caption\":\"BIM Indonesia\"},\"image\":{\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"Fan Fabrication &amp; Installation - BIM Indonesia","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"Fan Fabrication &amp; Installation - BIM Indonesia","og_url":"https:\/\/bim-indonesia.id\/index.php\/fan-fabrication-installation\/","og_site_name":"BIM Indonesia","article_modified_time":"2025-10-31T03:51:07+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bim-indonesia.id\/index.php\/fan-fabrication-installation\/","url":"https:\/\/bim-indonesia.id\/index.php\/fan-fabrication-installation\/","name":"Fan Fabrication &amp; Installation - BIM Indonesia","isPartOf":{"@id":"https:\/\/bim-indonesia.id\/#website"},"datePublished":"2025-10-31T03:50:58+00:00","dateModified":"2025-10-31T03:51:07+00:00","breadcrumb":{"@id":"https:\/\/bim-indonesia.id\/index.php\/fan-fabrication-installation\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bim-indonesia.id\/index.php\/fan-fabrication-installation\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bim-indonesia.id\/index.php\/fan-fabrication-installation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bim-indonesia.id\/"},{"@type":"ListItem","position":2,"name":"Fan Fabrication &amp; Installation"}]},{"@type":"WebSite","@id":"https:\/\/bim-indonesia.id\/#website","url":"https:\/\/bim-indonesia.id\/","name":"BIM Indonesia","description":"Innovation  *  Quality  *  Service","publisher":{"@id":"https:\/\/bim-indonesia.id\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bim-indonesia.id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/bim-indonesia.id\/#organization","name":"BIM Indonesia","url":"https:\/\/bim-indonesia.id\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bim-indonesia.id\/#\/schema\/logo\/image\/","url":"https:\/\/bim-indonesia.id\/bim-content\/uploads\/2024\/05\/cropped-WhatsApp-Image-2024-05-16-at-20.37.34.jpeg","contentUrl":"https:\/\/bim-indonesia.id\/bim-content\/uploads\/2024\/05\/cropped-WhatsApp-Image-2024-05-16-at-20.37.34.jpeg","width":1075,"height":1076,"caption":"BIM Indonesia"},"image":{"@id":"https:\/\/bim-indonesia.id\/#\/schema\/logo\/image\/"}}]}},"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/bim-indonesia.id\/index.php\/wp-json\/wp\/v2\/pages\/6026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bim-indonesia.id\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bim-indonesia.id\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bim-indonesia.id\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bim-indonesia.id\/index.php\/wp-json\/wp\/v2\/comments?post=6026"}],"version-history":[{"count":1,"href":"https:\/\/bim-indonesia.id\/index.php\/wp-json\/wp\/v2\/pages\/6026\/revisions"}],"predecessor-version":[{"id":6079,"href":"https:\/\/bim-indonesia.id\/index.php\/wp-json\/wp\/v2\/pages\/6026\/revisions\/6079"}],"wp:attachment":[{"href":"https:\/\/bim-indonesia.id\/index.php\/wp-json\/wp\/v2\/media?parent=6026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}