{"id":1174,"date":"2024-11-06T09:32:44","date_gmt":"2024-11-06T02:32:44","guid":{"rendered":"https:\/\/bim-indonesia.id\/?page_id=1174"},"modified":"2024-12-02T11:36:59","modified_gmt":"2024-12-02T04:36:59","slug":"mma-smaw-manual-metal-arc-shield-metal-arc-welding","status":"publish","type":"page","link":"https:\/\/bim-indonesia.id\/index.php\/mma-smaw-manual-metal-arc-shield-metal-arc-welding\/","title":{"rendered":"MMA \/ SMAW (Manual Metal Arc \/ Shield Metal Arc Welding)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1174\" class=\"elementor elementor-1174\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ff7e844 e-flex e-con-boxed e-con e-parent\" data-id=\"ff7e844\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-edc9fb1 de_scroll_animation_no elementor-widget elementor-widget-heading\" data-id=\"edc9fb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Coming soon<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Coming soon<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_eb_attr":"","site-sidebar-layout":"no-sidebar","site-content-layout":"","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-1174","page","type-page","status-publish","hentry"],"yoast_head":"<title>MMA \/ SMAW (Manual Metal Arc \/ Shield Metal Arc Welding) - BIM Indonesia<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MMA \/ SMAW (Manual Metal Arc \/ Shield Metal Arc Welding) - BIM Indonesia\" \/>\n<meta property=\"og:description\" content=\"Coming soon\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bim-indonesia.id\/index.php\/mma-smaw-manual-metal-arc-shield-metal-arc-welding\/\" \/>\n<meta property=\"og:site_name\" content=\"BIM Indonesia\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-02T04:36:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/index.php\\\/mma-smaw-manual-metal-arc-shield-metal-arc-welding\\\/\",\"url\":\"https:\\\/\\\/bim-indonesia.id\\\/index.php\\\/mma-smaw-manual-metal-arc-shield-metal-arc-welding\\\/\",\"name\":\"MMA \\\/ SMAW (Manual Metal Arc \\\/ Shield Metal Arc Welding) - BIM Indonesia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/#website\"},\"datePublished\":\"2024-11-06T02:32:44+00:00\",\"dateModified\":\"2024-12-02T04:36:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/index.php\\\/mma-smaw-manual-metal-arc-shield-metal-arc-welding\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bim-indonesia.id\\\/index.php\\\/mma-smaw-manual-metal-arc-shield-metal-arc-welding\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/index.php\\\/mma-smaw-manual-metal-arc-shield-metal-arc-welding\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bim-indonesia.id\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MMA \\\/ SMAW (Manual Metal Arc \\\/ Shield Metal Arc Welding)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/#website\",\"url\":\"https:\\\/\\\/bim-indonesia.id\\\/\",\"name\":\"BIM Indonesia\",\"description\":\"Innovation  *  Quality  *  Service\",\"publisher\":{\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bim-indonesia.id\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/#organization\",\"name\":\"BIM Indonesia\",\"url\":\"https:\\\/\\\/bim-indonesia.id\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/bim-indonesia.id\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-WhatsApp-Image-2024-05-16-at-20.37.34.jpeg\",\"contentUrl\":\"https:\\\/\\\/bim-indonesia.id\\\/wp-content\\\/uploads\\\/2024\\\/05\\\/cropped-WhatsApp-Image-2024-05-16-at-20.37.34.jpeg\",\"width\":1075,\"height\":1076,\"caption\":\"BIM Indonesia\"},\"image\":{\"@id\":\"https:\\\/\\\/bim-indonesia.id\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>","yoast_head_json":{"title":"MMA \/ SMAW (Manual Metal Arc \/ Shield Metal Arc Welding) - BIM Indonesia","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"MMA \/ SMAW (Manual Metal Arc \/ Shield Metal Arc Welding) - BIM Indonesia","og_description":"Coming soon","og_url":"https:\/\/bim-indonesia.id\/index.php\/mma-smaw-manual-metal-arc-shield-metal-arc-welding\/","og_site_name":"BIM Indonesia","article_modified_time":"2024-12-02T04:36:59+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bim-indonesia.id\/index.php\/mma-smaw-manual-metal-arc-shield-metal-arc-welding\/","url":"https:\/\/bim-indonesia.id\/index.php\/mma-smaw-manual-metal-arc-shield-metal-arc-welding\/","name":"MMA \/ SMAW (Manual Metal Arc \/ Shield Metal Arc Welding) - BIM Indonesia","isPartOf":{"@id":"https:\/\/bim-indonesia.id\/#website"},"datePublished":"2024-11-06T02:32:44+00:00","dateModified":"2024-12-02T04:36:59+00:00","breadcrumb":{"@id":"https:\/\/bim-indonesia.id\/index.php\/mma-smaw-manual-metal-arc-shield-metal-arc-welding\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bim-indonesia.id\/index.php\/mma-smaw-manual-metal-arc-shield-metal-arc-welding\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bim-indonesia.id\/index.php\/mma-smaw-manual-metal-arc-shield-metal-arc-welding\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bim-indonesia.id\/"},{"@type":"ListItem","position":2,"name":"MMA \/ SMAW (Manual Metal Arc \/ Shield Metal Arc Welding)"}]},{"@type":"WebSite","@id":"https:\/\/bim-indonesia.id\/#website","url":"https:\/\/bim-indonesia.id\/","name":"BIM Indonesia","description":"Innovation  *  Quality  *  Service","publisher":{"@id":"https:\/\/bim-indonesia.id\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bim-indonesia.id\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/bim-indonesia.id\/#organization","name":"BIM Indonesia","url":"https:\/\/bim-indonesia.id\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/bim-indonesia.id\/#\/schema\/logo\/image\/","url":"https:\/\/bim-indonesia.id\/bim-content\/uploads\/2024\/05\/cropped-WhatsApp-Image-2024-05-16-at-20.37.34.jpeg","contentUrl":"https:\/\/bim-indonesia.id\/bim-content\/uploads\/2024\/05\/cropped-WhatsApp-Image-2024-05-16-at-20.37.34.jpeg","width":1075,"height":1076,"caption":"BIM Indonesia"},"image":{"@id":"https:\/\/bim-indonesia.id\/#\/schema\/logo\/image\/"}}]}},"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/bim-indonesia.id\/index.php\/wp-json\/wp\/v2\/pages\/1174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bim-indonesia.id\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bim-indonesia.id\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bim-indonesia.id\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bim-indonesia.id\/index.php\/wp-json\/wp\/v2\/comments?post=1174"}],"version-history":[{"count":0,"href":"https:\/\/bim-indonesia.id\/index.php\/wp-json\/wp\/v2\/pages\/1174\/revisions"}],"wp:attachment":[{"href":"https:\/\/bim-indonesia.id\/index.php\/wp-json\/wp\/v2\/media?parent=1174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}